{"id":157,"date":"2024-08-30T16:32:03","date_gmt":"2024-08-30T19:32:03","guid":{"rendered":"https:\/\/helpcorretora.com.br\/help-na-saude\/?p=157"},"modified":"2024-09-08T14:53:11","modified_gmt":"2024-09-08T17:53:11","slug":"help-corretora-lanca-canal-no-youtube","status":"publish","type":"post","link":"https:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/","title":{"rendered":"Help Corretora lan\u00e7a canal no Youtube!"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Agora estamos prontos para novos desafios.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong><a href=\"https:\/\/helpcorretora.com.br\/\">Help Corretora<\/a> <\/strong>acaba de dar um passo ousado e inovador: o lan\u00e7amento oficial do seu canal no YouTube! No dia 29 de agosto, data emblem\u00e1tica tamb\u00e9m conhecida como o &#8220;dia do ju\u00edzo final&#8221; pelo ic\u00f4nico Kyle Reese, o Head de Marketing Nelson Galv\u00e3o apresentou, de forma surpreendente, o canal <a href=\"https:\/\/www.youtube.com\/@helpcorretoraoficial\">@<em>helpcorretoraoficial<\/em><\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/mary_011-300x300.png\" alt=\"\" class=\"wp-image-159\" srcset=\"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/mary_011-300x300.png 300w, https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/mary_011-150x150.png 150w, https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/mary_011-768x768.png 768w, https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/mary_011.png 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Com uma estr\u00e9ia digna de aplausos, a princ\u00edpio dois v\u00eddeos foram apresentados na pr\u00f3pria plataforma, com a carism\u00e1tica assistente virtual <strong>Mary Help<\/strong> \u00e0 frente. Em primeiro lugar ela guiou o p\u00fablico por uma jornada fascinante, destacando a nova intranet da empresa e revelando segredos sobre como capturar clientes de forma org\u00e2nica usando as redes sociais. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Youtube, uma importante ferramenta de pesquisa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;O YouTube \u00e9 a segunda maior ferramenta de busca na internet. E, vamos ser sinceros, os brasileiros preferem ver do que ler, por isso n\u00e3o pod\u00edamos ficar de fora!&#8221;, afirma Galv\u00e3o, com a vis\u00e3o afiada de quem entende de marketing. Ele ainda revela: &#8220;Com a agenda dos gestores lotada, decidimos criar uma personagem virtual, dispon\u00edvel 24\/7, pronta para gravar sempre que necess\u00e1rio. Usamos um conjunto de ferramentas de IA para dar vida aos v\u00eddeos, e os resultados est\u00e3o superando nossas expectativas!&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O canal j\u00e1 nasce sobretudo estruturado e com conte\u00fado de peso: s\u00e3o 6 v\u00eddeos e 3 playlists imperd\u00edveis. Em <em>Help Apresenta<\/em>, conhe\u00e7a as empresas parceiras; <em>Por dentro da Help<\/em> oferece conte\u00fados para colaboradores que tamb\u00e9m interessam ao p\u00fablico em geral; e <em>Por dentro dos Planos<\/em> aborda tudo sobre benef\u00edcios, \u00e1reas de cobertura, servi\u00e7os e o dia a dia das operadoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Em primeiro lugar as novidades n\u00e3o param por a\u00ed! Vem a\u00ed o <em>POD HELP<\/em>, um podcast que ser\u00e1 conduzido pelo pr\u00f3prio CEO da empresa, trazendo convidados especiais do universo dos planos e seguros sa\u00fade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o perca tempo! Inscreva-se agora, ative as notifica\u00e7\u00f5es, curta e compartilhe para n\u00e3o perder nenhum detalhe dessa revolu\u00e7\u00e3o digital que a Help Corretora est\u00e1 liderando. ?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea \u00e9 nosso convidado a se inscrever, curtir, ativar as notifica\u00e7\u00f5es e compartilhar nosso conte\u00fado. <a href=\"https:\/\/www.youtube.com\/@helpcorretoraoficial\">Clique aqui e inscreva-se!<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agora estamos prontos para novos desafios. A Help Corretora acaba de dar um passo ousado e inovador: o lan\u00e7amento oficial do seu canal no YouTube! No dia 29 de agosto, data emblem\u00e1tica tamb\u00e9m conhecida como o &#8220;dia do ju\u00edzo final&#8221; pelo ic\u00f4nico Kyle Reese, o Head de Marketing Nelson Galv\u00e3o apresentou, de forma surpreendente, o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[47,50,48,49,46],"class_list":["post-157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia-e-internet","tag-ia","tag-marketing","tag-mary-help","tag-pod-help","tag-youtube"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Help Corretora lan\u00e7a canal no Youtube! - Help! na sa\u00fade<\/title>\n<meta name=\"description\" content=\"Help Corretora lan\u00e7a canal no Youtube! Agora estamos prontos para novos desafios. Inscreva-se no canal e fique sempre atualizado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Help Corretora lan\u00e7a canal no Youtube! - Help! na sa\u00fade\" \/>\n<meta property=\"og:description\" content=\"Help Corretora lan\u00e7a canal no Youtube! Agora estamos prontos para novos desafios. Inscreva-se no canal e fique sempre atualizado.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/\" \/>\n<meta property=\"og:site_name\" content=\"Help! na sa\u00fade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/planosdesaudehelp\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T19:32:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-08T17:53:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"helpcorretora\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"helpcorretora\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/\"},\"author\":{\"name\":\"helpcorretora\",\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/person\/e7d808b786faee401dc61da20dddec21\"},\"headline\":\"Help Corretora lan\u00e7a canal no Youtube!\",\"datePublished\":\"2024-08-30T19:32:03+00:00\",\"dateModified\":\"2024-09-08T17:53:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#organization\"},\"image\":{\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp\",\"keywords\":[\"IA\",\"Marketing\",\"Mary Help\",\"Pod Help\",\"youtube\"],\"articleSection\":[\"Tecnologia e Internet\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/\",\"url\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/\",\"name\":\"Help Corretora lan\u00e7a canal no Youtube! - Help! na sa\u00fade\",\"isPartOf\":{\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp\",\"datePublished\":\"2024-08-30T19:32:03+00:00\",\"dateModified\":\"2024-09-08T17:53:11+00:00\",\"description\":\"Help Corretora lan\u00e7a canal no Youtube! Agora estamos prontos para novos desafios. Inscreva-se no canal e fique sempre atualizado.\",\"breadcrumb\":{\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#primaryimage\",\"url\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp\",\"contentUrl\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp\",\"width\":1200,\"height\":651},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Corretora lan\u00e7a canal no Youtube!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#website\",\"url\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/\",\"name\":\"Help! na sa\u00fade\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#organization\",\"name\":\"Help! na sa\u00fade\",\"url\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/cropped-image.png\",\"contentUrl\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/cropped-image.png\",\"width\":108,\"height\":60,\"caption\":\"Help! na sa\u00fade\"},\"image\":{\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/planosdesaudehelp\",\"https:\/\/www.instagram.com\/helpcorretoraoficial\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/person\/e7d808b786faee401dc61da20dddec21\",\"name\":\"helpcorretora\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6e79772589d76b400d28b696454b7cc70690548aee94d5299c46acdcaebde63d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6e79772589d76b400d28b696454b7cc70690548aee94d5299c46acdcaebde63d?s=96&d=mm&r=g\",\"caption\":\"helpcorretora\"},\"sameAs\":[\"http:\/\/helpcorretora.com.br\/help-na-saude\"],\"url\":\"https:\/\/helpcorretora.com.br\/help-na-saude\/author\/helpcorretora\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Help Corretora lan\u00e7a canal no Youtube! - Help! na sa\u00fade","description":"Help Corretora lan\u00e7a canal no Youtube! Agora estamos prontos para novos desafios. Inscreva-se no canal e fique sempre atualizado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/","og_locale":"pt_BR","og_type":"article","og_title":"Help Corretora lan\u00e7a canal no Youtube! - Help! na sa\u00fade","og_description":"Help Corretora lan\u00e7a canal no Youtube! Agora estamos prontos para novos desafios. Inscreva-se no canal e fique sempre atualizado.","og_url":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/","og_site_name":"Help! na sa\u00fade","article_publisher":"https:\/\/www.facebook.com\/planosdesaudehelp","article_published_time":"2024-08-30T19:32:03+00:00","article_modified_time":"2024-09-08T17:53:11+00:00","og_image":[{"width":1200,"height":651,"url":"http:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp","type":"image\/webp"}],"author":"helpcorretora","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"helpcorretora","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#article","isPartOf":{"@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/"},"author":{"name":"helpcorretora","@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/person\/e7d808b786faee401dc61da20dddec21"},"headline":"Help Corretora lan\u00e7a canal no Youtube!","datePublished":"2024-08-30T19:32:03+00:00","dateModified":"2024-09-08T17:53:11+00:00","mainEntityOfPage":{"@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#organization"},"image":{"@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#primaryimage"},"thumbnailUrl":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp","keywords":["IA","Marketing","Mary Help","Pod Help","youtube"],"articleSection":["Tecnologia e Internet"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/","url":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/","name":"Help Corretora lan\u00e7a canal no Youtube! - Help! na sa\u00fade","isPartOf":{"@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#website"},"primaryImageOfPage":{"@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#primaryimage"},"image":{"@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#primaryimage"},"thumbnailUrl":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp","datePublished":"2024-08-30T19:32:03+00:00","dateModified":"2024-09-08T17:53:11+00:00","description":"Help Corretora lan\u00e7a canal no Youtube! Agora estamos prontos para novos desafios. Inscreva-se no canal e fique sempre atualizado.","breadcrumb":{"@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#primaryimage","url":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp","contentUrl":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/bd-posts12.webp","width":1200,"height":651},{"@type":"BreadcrumbList","@id":"http:\/\/helpcorretora.com.br\/help-na-saude\/help-corretora-lanca-canal-no-youtube\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/helpcorretora.com.br\/help-na-saude\/"},{"@type":"ListItem","position":2,"name":"Help Corretora lan\u00e7a canal no Youtube!"}]},{"@type":"WebSite","@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#website","url":"https:\/\/helpcorretora.com.br\/help-na-saude\/","name":"Help! na sa\u00fade","description":"","publisher":{"@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/helpcorretora.com.br\/help-na-saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#organization","name":"Help! na sa\u00fade","url":"https:\/\/helpcorretora.com.br\/help-na-saude\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/logo\/image\/","url":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/cropped-image.png","contentUrl":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-content\/uploads\/2024\/08\/cropped-image.png","width":108,"height":60,"caption":"Help! na sa\u00fade"},"image":{"@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/planosdesaudehelp","https:\/\/www.instagram.com\/helpcorretoraoficial\/"]},{"@type":"Person","@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/person\/e7d808b786faee401dc61da20dddec21","name":"helpcorretora","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/helpcorretora.com.br\/help-na-saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6e79772589d76b400d28b696454b7cc70690548aee94d5299c46acdcaebde63d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e79772589d76b400d28b696454b7cc70690548aee94d5299c46acdcaebde63d?s=96&d=mm&r=g","caption":"helpcorretora"},"sameAs":["http:\/\/helpcorretora.com.br\/help-na-saude"],"url":"https:\/\/helpcorretora.com.br\/help-na-saude\/author\/helpcorretora\/"}]}},"_links":{"self":[{"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/posts\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":3,"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/posts\/157\/revisions"}],"predecessor-version":[{"id":275,"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/posts\/157\/revisions\/275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/media\/158"}],"wp:attachment":[{"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/media?parent=157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/categories?post=157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/helpcorretora.com.br\/help-na-saude\/wp-json\/wp\/v2\/tags?post=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}